﻿{"id":2138,"date":"2015-06-19T19:07:41","date_gmt":"2015-06-19T23:37:41","guid":{"rendered":"http:\/\/motores.com.ve\/motoresven\/?p=2138"},"modified":"2015-06-19T19:09:27","modified_gmt":"2015-06-19T23:39:27","slug":"pastor-cuarto-en-austria","status":"publish","type":"post","link":"https:\/\/motores.com.ve\/motoresven\/pastor-cuarto-en-austria\/","title":{"rendered":"PASTOR CUARTO EN AUSTRIA"},"content":{"rendered":"<p><a href=\"http:\/\/motores.com.ve\/motoresven\/wp-content\/uploads\/2015\/06\/pastormaldonado149_600.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-medium wp-image-2139\" src=\"http:\/\/motores.com.ve\/motoresven\/wp-content\/uploads\/2015\/06\/pastormaldonado149_600-300x165.jpg\" alt=\"pastormaldonado149_600\" width=\"300\" height=\"165\" srcset=\"https:\/\/motores.com.ve\/motoresven\/wp-content\/uploads\/2015\/06\/pastormaldonado149_600-300x165.jpg 300w, https:\/\/motores.com.ve\/motoresven\/wp-content\/uploads\/2015\/06\/pastormaldonado149_600.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\u2022 El maracayero se mostr\u00f3 solvente en las dos tandas con su E23, monoplaza que respondi\u00f3 a los cambios de puesta a punto. \u201cCreo que podremos mantenernos por este entorno en el fin de semana, ya que nuestro objetivo son los puntos. A\u00fan quedan cosas por mejorar y a eso iremos en la \u00faltima pr\u00e1ctica\u201d destac\u00f3 Maldonado.<\/p>\n<p>******************************************************************<\/p>\n<p>Como producto de la alternancia de escenarios aerodin\u00e1micos y con el reto permanente de conseguir la temperatura adecuada en pista, el piloto venezolano Pastor Maldonado se mostr\u00f3 solvente y satisfecho con su E23 en el trazado Spielberg de Austria, donde logr\u00f3 el cuarto mejor tiempo en la tanda vespertina de ensayos libres, luego de ubicarse duod\u00e9cimo en el turno matutino, a\u00fan con el logro de buenos cronos parciales.<\/p>\n<p>\u201cHa sido un d\u00eda de mucha actividad tanto en pista como fuera de ella, hemos logrado una buena posici\u00f3n y en este entorno esperamos mantenernos en lo que resta de fin de semana, ya que nuestro objetivo son los puntos. Hicimos cambios importantes en la puesta a punto, as\u00ed como en la electr\u00f3nica y el coche respondi\u00f3 bien y esto demuestra que tenemos la capacidad de adaptarnos a cualquier circuito. Si bien es cierto que algunos equipos no lograron buenas vueltas hoy, creo que seguiremos en la lucha\u201d explic\u00f3 Pastor al t\u00e9rmino de su jornada.<\/p>\n<p>El volante patrocinado por PDVSA, realiz\u00f3 treinta y cuatro vueltas en la ma\u00f1ana y contabiliz\u00f3 cuarenta y cuatro en la tarde para totalizar setenta y ocho en su haber, como uno de los pilotos con mayor cantidad de giros durante las dos tandas de hora y media. \u201cEn la ma\u00f1ana encontramos un circuito resbaloso con poco agarre, pero fue mejorando. Tuvimos cielo nublado y ello influy\u00f3 en el calentamiento de las gomas, sobre todo en las primeras vueltas; enfrentamos adem\u00e1s algunos problemas con la aerodin\u00e1mica, que nos hacen perder d\u00e9cimas, pero all\u00ed estamos\u201d agreg\u00f3.<\/p>\n<p>El criollo relat\u00f3 que las alternativas de puesta a punto funcionaron casi todas, a\u00fan en la ma\u00f1ana, cuando marc\u00f3 buenos tiempos parciales, pero no pudo completar ninguna vuelta limpia, que le permitiera unir los tres sectores y ubicarse m\u00e1s adelante, seg\u00fan el ritmo que ven\u00eda mostrando el E23. Nico Rosberg (Mercedes) lider\u00f3 la ma\u00f1ana y Sebastian Vettel (Ferrari) fue el m\u00e1s r\u00e1pido en la tarde.<\/p>\n<p>Para el ganador del GP de Espa\u00f1a 2012, la peque\u00f1a p\u00e9rdida aerodin\u00e1mica proveniente del piso del auto, ser\u00e1 menos severa en este circuito, con respecto a Canad\u00e1. \u201cVamos a hacer algunas pruebas para mejorar esto. Ahora viene la \u00faltima pr\u00e1ctica, donde probaremos con menos gasolina y las gomas s\u00faper blandas en configuraci\u00f3n de clasificaci\u00f3n y es all\u00ed donde vamos a buscar el mejor balance posible para tener un auto rendidor tanto en clasificaci\u00f3n como en carrera.\u201d<\/p>\n<p>Para el turno de la ma\u00f1ana, la estrategia de Lotus se enfoc\u00f3 en pruebas aerodin\u00e1micas, calibraci\u00f3n del consumo de cauchos e incluso recorridos largos con tanque lleno para evaluar el comportamiento de los frenos. En la tarde continu\u00f3 la evaluaci\u00f3n de gomas y los recorridos con tanque lleno, adem\u00e1s de vueltas r\u00e1pidas tempranas con las gomas s\u00faper suaves. En la primera tanda, el uso de gomas se limit\u00f3 al componente suave y en la tarde se altern\u00f3 con el s\u00faper suave.<\/p>\n<p>Maldonado inform\u00f3 que la degradaci\u00f3n es baja en el trazado austr\u00edaco. Eso fue lo que experimentamos: vamos a esperar el informe de Pirelli para tomar decisiones. En cuanto a la temperatura, el componente s\u00faper suave se comport\u00f3 mejor, mientras que con el componente suave resulta un poco m\u00e1s complicado obtener la temperatura correcta para que trabaje bien\u201d.<\/p>\n<p>La agenda del GP de Austria prosigue con la tercera y \u00faltima pr\u00e1ctica a las 4:30 am venezolana. La clasificaci\u00f3n ser\u00e1 a las 7:30 am y la carrera se iniciar\u00e1 a la misma hora del d\u00eda domingo.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>A continuaci\u00f3n, los tiempos oficiales de las dos sesiones de ensayos libres en Spielberg. Fuente: www.formula1.com<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>PRIMER TURNO<\/strong><\/p>\n<p>1 &#8211; Nico Rosberg (Mercedes W06) &#8211; 1&#8217;10&#8243;401 \u2013 35 vueltas<br \/>\n2 &#8211; Lewis Hamilton (Mercedes W06) &#8211; 1&#8217;10&#8243;709 \u2013 28<br \/>\n3 &#8211; Kimi Raikkonen (Ferrari SF15-T) &#8211; 1&#8217;11&#8243;028 &#8211; 22<br \/>\n4 &#8211; Valtteri Bottas (Williams FW37-Mercedes) &#8211; 1&#8217;11&#8243;452 &#8211; 26<br \/>\n5 &#8211; Felipe Nasr (Sauber C34-Ferrari) &#8211; 1&#8217;11&#8243;633 &#8211; 28<br \/>\n6 &#8211; Daniil Kvyat (Red Bull RB11-Renault) &#8211; 1&#8217;11&#8243;642 &#8211; 31<br \/>\n7 &#8211; Daniel Ricciardo (Red Bull RB11-Renault) &#8211; 1&#8217;11&#8243;724 &#8211; 29<br \/>\n8 &#8211; Max Verstappen (Toro Rosso STR10-Renault) &#8211; 1&#8217;18&#8243;825 &#8211; 38<br \/>\n9 &#8211; Felipe Massa (Williams FW37-Mercedes) &#8211; 1&#8217;11&#8243;890 &#8211; 29<br \/>\n10 &#8211; Sergio Perez (Force India VJM08-Mercedes) &#8211; 1&#8217;11&#8243;905 &#8211; 37<br \/>\n11 &#8211; Carlos Sainz (Toro Rosso STR10-Renault) &#8211; 1&#8217;11&#8243;948 &#8211; 32<br \/>\n<strong>12 &#8211; PASTOR MALDONADO (Lotus E23-Mercedes) &#8211; 1&#8217;12&#8243;004 &#8211; 34<\/strong><br \/>\n13 &#8211; Nico Hulkenberg (Force India VJM08-Mercedes) &#8211; 1&#8217;12&#8243;031 &#8211; 36<br \/>\n14 \u2013 Jolyon Palmer (Lotus E23-Mercedes) &#8211; 1&#8217;12&#8243;050 &#8211; 27<br \/>\n15 &#8211; Marcus Ericsson (Sauber C34-Ferrari) &#8211; 1&#8217;12&#8243;159 &#8211; 30<br \/>\n16 &#8211; Jenson Button (McLaren MP4\/30-Honda) &#8211; 1&#8217;12&#8243;920 &#8211; 30<br \/>\n17 &#8211; Fernando Alonso (McLaren MP4\/30-Honda) &#8211; 1&#8217;13&#8243;272 &#8211; 10<br \/>\n18 &#8211; Will Stevens (Manor 04-Ferrari) &#8211; 1&#8217;13&#8243;937 &#8211; 29<br \/>\n19 &#8211; Roberto Merhi (Manor 04-Ferrari) &#8211; 1&#8217;15&#8243;459 \u2013 11<br \/>\n20 &#8211; Sebastian Vettel (Ferrari SF15-T) &#8211; 1&#8217;15&#8243;684 \u2013 4<\/p>\n<p>&nbsp;<\/p>\n<p><strong>SEGUNDO TURNO<\/strong><\/p>\n<p>1 &#8211; Sebastian Vettel (Ferrari SF15-T) &#8211; 1&#8217;09&#8243;600 \u2013 28 vueltas<br \/>\n2 &#8211; Nico Rosberg (Mercedes W06) &#8211; 1&#8217;09&#8243;611 \u2013 50<br \/>\n3 &#8211; Kimi Raikkonen (Ferrari SF15-T) &#8211; 1&#8217;09&#8243;860 &#8211; 41<br \/>\n<strong>4 &#8211; PASTOR MALDONADO (Lotus E23-Mercedes) &#8211; 1&#8217;09&#8243;914 &#8211; 44<\/strong><br \/>\n5 &#8211; Lewis Hamilton (Mercedes W06) &#8211; 1&#8217;10&#8243;137 \u2013 49<br \/>\n6 &#8211; Nico Hulkenberg (Force India VJM08-Mercedes) &#8211; 1&#8217;10&#8243;160 &#8211; 49<br \/>\n7 \u2013 Romain Grosjean (Lotus E23-Mercedes) &#8211; 1&#8217;10&#8243;267 &#8211; 38<br \/>\n8 &#8211; Max Verstappen (Toro Rosso STR10-Renault) &#8211; 1&#8217;10&#8243;356 &#8211; 48<br \/>\n9 &#8211; Felipe Nasr (Sauber C34-Ferrari) &#8211; 1&#8217;10&#8243;495 &#8211; 39<br \/>\n10 &#8211; Sergio Perez (Force India VJM08-Mercedes) &#8211; 1&#8217;10&#8243;585 &#8211; 46<br \/>\n11 &#8211; Carlos Sainz (Toro Rosso STR10-Renault) &#8211; 1&#8217;10&#8243;631 &#8211; 50<br \/>\n12 &#8211; Daniil Kvyat (Red Bull RB11-Renault) &#8211; 1&#8217;10&#8243;686 &#8211; 48<br \/>\n13 &#8211; Marcus Ericsson (Sauber C34-Ferrari) &#8211; 1&#8217;10&#8243;744 &#8211; 30<br \/>\n14 &#8211; Valtteri Bottas (Williams FW37-Mercedes) &#8211; 1&#8217;10&#8243;746 &#8211; 34<br \/>\n15 &#8211; Felipe Massa (Williams FW37-Mercedes) &#8211; 1&#8217;11&#8243;011 &#8211; 42<br \/>\n16 &#8211; Fernando Alonso (McLaren MP4\/30-Honda) &#8211; 1&#8217;11&#8243;517 &#8211; 17<br \/>\n17 &#8211; Daniel Ricciardo (Red Bull RB11-Renault) &#8211; 1&#8217;11&#8243;676 &#8211; 38<br \/>\n18 &#8211; Jenson Button (McLaren MP4\/30-Honda) &#8211; 1&#8217;11&#8243;919 &#8211; 17<br \/>\n19 &#8211; Will Stevens (Manor 04-Ferrari) &#8211; 1&#8217;12&#8243;522 &#8211; 34<br \/>\n20 &#8211; Roberto Merhi (Manor 04-Ferrari) &#8211; 1&#8217;13&#8243;094 \u2013 34<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Prensa Pastor Maldonado \/ Arturo Mora<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2022 El maracayero se mostr\u00f3 solvente en las dos tandas con su E23, monoplaza que respondi\u00f3 a los cambios de puesta a punto. \u201cCreo que podremos mantenernos por este entorno en el fin de semana, ya que nuestro objetivo son los puntos. A\u00fan quedan cosas por mejorar y a eso iremos en la \u00faltima pr\u00e1ctica\u201d &#8230;<\/p>\n","protected":false},"author":2,"featured_media":2139,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3,5],"tags":[],"_links":{"self":[{"href":"https:\/\/motores.com.ve\/motoresven\/wp-json\/wp\/v2\/posts\/2138"}],"collection":[{"href":"https:\/\/motores.com.ve\/motoresven\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/motores.com.ve\/motoresven\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/motores.com.ve\/motoresven\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/motores.com.ve\/motoresven\/wp-json\/wp\/v2\/comments?post=2138"}],"version-history":[{"count":3,"href":"https:\/\/motores.com.ve\/motoresven\/wp-json\/wp\/v2\/posts\/2138\/revisions"}],"predecessor-version":[{"id":2142,"href":"https:\/\/motores.com.ve\/motoresven\/wp-json\/wp\/v2\/posts\/2138\/revisions\/2142"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/motores.com.ve\/motoresven\/wp-json\/wp\/v2\/media\/2139"}],"wp:attachment":[{"href":"https:\/\/motores.com.ve\/motoresven\/wp-json\/wp\/v2\/media?parent=2138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/motores.com.ve\/motoresven\/wp-json\/wp\/v2\/categories?post=2138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/motores.com.ve\/motoresven\/wp-json\/wp\/v2\/tags?post=2138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}