﻿{"id":2331,"date":"2015-11-23T23:31:33","date_gmt":"2015-11-24T04:01:33","guid":{"rendered":"http:\/\/motores.com.ve\/motoresven\/?p=2331"},"modified":"2016-01-06T23:35:02","modified_gmt":"2016-01-07T04:05:02","slug":"pastor-a-cerrar-con-produccion-en-abu-dhabi-2","status":"publish","type":"post","link":"http:\/\/motores.com.ve\/motoresven\/pastor-a-cerrar-con-produccion-en-abu-dhabi-2\/","title":{"rendered":"PASTOR A CERRAR CON PRODUCCI\u00d3N EN ABU DHABI"},"content":{"rendered":"<p><a href=\"http:\/\/motores.com.ve\/motoresven\/wp-content\/uploads\/2015\/07\/pastormaldonado150_600.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-2201\" src=\"http:\/\/motores.com.ve\/motoresven\/wp-content\/uploads\/2015\/07\/pastormaldonado150_600-300x165.jpg\" alt=\"pastormaldonado150_600\" width=\"300\" height=\"165\" srcset=\"http:\/\/motores.com.ve\/motoresven\/wp-content\/uploads\/2015\/07\/pastormaldonado150_600-300x165.jpg 300w, http:\/\/motores.com.ve\/motoresven\/wp-content\/uploads\/2015\/07\/pastormaldonado150_600.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\u2022 Enfocados en proyecto del auto 2016, tanto el criollo como su equipo no descuidan la preparaci\u00f3n para este fin de semana, en el que aspiran culminar con buen pie la temporada y llevar puntos importantes a casa.<\/p>\n<p>\u2022 En 2012, Maldonado marc\u00f3 el cuarto mejor tiempo en clasificaci\u00f3n, larg\u00f3 en segunda fila y cruz\u00f3 la meta en quinto lugar sobre el asfalto del Yas Marina Circuit, aun cuando su Kers qued\u00f3 inutilizado al inicio de la competencia.<\/p>\n<p>\u2022 El maracayero ha facturado en tres de las cuatro \u00faltimas carreras, quedando al ras de los puntos en M\u00e9xico por la exagerada sanci\u00f3n que le sac\u00f3 del top ten.<\/p>\n<p>****************************************************************<\/p>\n<p>Con el objetivo de obtener puntos importantes en el cierre de la zafra 2015, el piloto venezolano Pastor Maldonado y su equipo Lotus se encuentran ya en territorio \u00e1rabe, iniciando los preparativos de participaci\u00f3n en la XIX V\u00e1lida de la F\u00f3rmula 1, cuyo tel\u00f3n caer\u00e1 este fin de semana en el Yas Marina Circuit de Abu Dhabi, donde la escuadra aurinegra buscar\u00e1 adem\u00e1s asegurar su puesto en la tabla de constructores.<\/p>\n<p>El de Maracay afronta el compromiso de cerrar con producci\u00f3n una temporada de altibajos, en cuya parte final ha venido marcando en forma sistem\u00e1tica, con tres top ten en cuatro carreras. \u201cSiempre es especial correr ac\u00e1: el ambiente es insuperable y trat\u00e1ndose del cierre, todos deseamos culminar con buen papel: venimos con ritmo estable, a pesar de las conocidas limitaciones del coche en sus actualizaciones y mejoras, as\u00ed que apuntamos a un cierre con puntos para llevar a casa.\u201d<\/p>\n<p>El volante auspiciado por PDVSA, acumula experiencia en el fastuoso trazado de 5.554 metros. \u201cEs un Circuito t\u00e9cnico, de muy gratos recuerdos, donde realic\u00e9 las pruebas que me impulsaron a la F\u00f3rmula 1. Tiene curvas lentas y rectas largas, un tanto semejante a Singapur. En el inolvidable 2012, tuvimos un fin de semana productivo ac\u00e1 al clasificar en cuarto lugar y luego en carrera culminamos quintos, a pesar de tener el sistema KERS da\u00f1ado.\u201d<\/p>\n<p>El arag\u00fce\u00f1o se siente c\u00f3modo en este dibujo. \u201cMe encanta el primer sector, que es muy r\u00e1pido, concretamente las curvas dos, tres y cuatro; el segundo tiene curvas que se toman en segunda velocidad, aderezadas con chicanas para finalizar en el sector tres, que es muy pintoresco. El equipo acumula data de seis carreras previas, lo que ser\u00e1 muy \u00fatil en la retadora puesta a punto de esta carrera, en la que largas con bastante calor y luz natural pero al ponerse el sol, la temperatura baja dr\u00e1sticamente y vas en luz artificial, por lo que tu coche debe ser efectivo en ambos escenarios. Adem\u00e1s, siempre hay arena en la pista con la que hay que lidiar.\u201d<\/p>\n<p>Por su parte, Nick Chester Director T\u00e9cnico de Lotus, esboz\u00f3 los escenarios de probabilidades. \u201cEl primer sector es en general de velocidad media, con un par de curvas donde vas en alta; es sencillo desde el punto de vista t\u00e9cnico y basta con un nivel razonable de carga aerodin\u00e1mica. El segundo tramo requiere mayor potencia: tiene dos buenas rectas y un par de curvas lentas, que deben ser tratadas con sumo cuidado, mientras que el tercer sector es m\u00e1s t\u00e9cnico con curvas de mediana y baja velocidad, donde el coche necesita estar bien balanceado y trabajar bien para lograr buen tiempo en la vuelta: en resumen, necesitas un coche que funcione bien en las curvas lentas y que sea eficaz en las rectas.\u201d<\/p>\n<p>El balance 2015 de Chester, se resume en pocas palabras: Estoy contento con el E23 en muchos aspectos, pero a la vez insatisfecho en t\u00e9rminos de su desarrollo: hicimos un buen auto base que funciona bien, del cual nuestros pilotos pudieron extraer mucho. Lamentablemente no tuvimos el desarrollo planificado por razones financieras, de lo contrario hubi\u00e9semos visto cosas muy interesantes en la pista a lo largo del a\u00f1o. Sin embargo, aprendimos mucho y llevaremos esto al coche de 2016\u201d.<br \/>\n<strong>LA CARRERA DE BRASIL<\/strong><\/p>\n<p>Pastor consigui\u00f3 un punto en la \u00faltima parada americana 2015 de la F\u00f3rmula 1, al realizar una carrera meritoria. \u201cLamentablemente no clasificamos donde quer\u00edamos y en carrera usamos diferentes estrategias con los cauchos, de manera de poder atacar desde atr\u00e1s. Hicimos buena carrera: un poco de paciencia en la largada con gomas duras, cuando los dem\u00e1s ten\u00edan cauchos blandos y luego, presionar con fuerza cuando ten\u00edamos llantas blandas y los rivales, duras. Funcion\u00f3 bien, aun cuando fue frustrante en las vueltas finales ver a otros con gomas m\u00e1s r\u00e1pidas, pero en fin un d\u00e9cimo lugar, largando desde el puesto quince a estas alturas de la temporada, fe un resultado positivo.\u201d<\/p>\n<p>\u201cFue decepcionante el carro en clasificaci\u00f3n luego de buenos indicios en la \u00faltima pr\u00e1ctica del s\u00e1bado. Nuestro pilotos hicieron buenas carreras y nos llevamos a casa cinco puntos, sin duda merecidos\u201d dijo Nick Chester.<br \/>\n<strong>EL PROGRAMA<\/strong><\/p>\n<p>La \u00faltima cita 2015 de la m\u00e1xima categor\u00eda, contempla en su agenda el inicio de la primera pr\u00e1ctica a las 4:30 de la madrugada del viernes (hora de Venezuela) mientras que la segunda tanda de hora y media, ser\u00e1 a las 8:30 am. Los \u00faltimos ensayos colectivos, comienzan en la madrugada sabatina (5:30 am) y la clasificaci\u00f3n tendr\u00e1 lugar a las 8:30 am, para definir la grilla del GP de Abu Dhabi, cuya largada est\u00e1 prevista para las 8:30 am del domingo, con cincuenta y cinco vueltas sobre los 5.554 metros del trazado \u00e1rabe.<\/p>\n<p><strong>Prensa Pastor Maldonado \/ Arturo Mora<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2022 Enfocados en proyecto del auto 2016, tanto el criollo como su equipo no descuidan la preparaci\u00f3n para este fin de semana, en el que aspiran culminar con buen pie la temporada y llevar puntos importantes a casa. \u2022 En &hellip; <a href=\"http:\/\/motores.com.ve\/motoresven\/pastor-a-cerrar-con-produccion-en-abu-dhabi-2\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":2201,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,5],"tags":[],"_links":{"self":[{"href":"http:\/\/motores.com.ve\/motoresven\/wp-json\/wp\/v2\/posts\/2331"}],"collection":[{"href":"http:\/\/motores.com.ve\/motoresven\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/motores.com.ve\/motoresven\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/motores.com.ve\/motoresven\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/motores.com.ve\/motoresven\/wp-json\/wp\/v2\/comments?post=2331"}],"version-history":[{"count":1,"href":"http:\/\/motores.com.ve\/motoresven\/wp-json\/wp\/v2\/posts\/2331\/revisions"}],"predecessor-version":[{"id":2332,"href":"http:\/\/motores.com.ve\/motoresven\/wp-json\/wp\/v2\/posts\/2331\/revisions\/2332"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/motores.com.ve\/motoresven\/wp-json\/wp\/v2\/media\/2201"}],"wp:attachment":[{"href":"http:\/\/motores.com.ve\/motoresven\/wp-json\/wp\/v2\/media?parent=2331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/motores.com.ve\/motoresven\/wp-json\/wp\/v2\/categories?post=2331"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/motores.com.ve\/motoresven\/wp-json\/wp\/v2\/tags?post=2331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}